{"id":4332,"date":"2025-06-14T01:53:24","date_gmt":"2025-06-14T01:53:24","guid":{"rendered":"https:\/\/dreamslab.bravisthemes.com\/?page_id=4332"},"modified":"2026-06-03T19:37:00","modified_gmt":"2026-06-03T22:37:00","slug":"projetos","status":"publish","type":"page","link":"https:\/\/dezetoro.com\/br\/projetos\/","title":{"rendered":"Projetos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4332\" class=\"elementor elementor-4332\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d36af36 e-con-full e-flex pxl-row-scroll-none pxl-column-none pxl-full-content-with-space-none e-con e-parent \" data-id=\"d36af36\" data-element_type=\"container\" data-e-type=\"container\">\t\t<div class=\"elementor-element elementor-element-9bb514c pxl-post-layout-portfolio-1 elementor-widget elementor-widget-pxl_post_grid\" data-id=\"9bb514c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pxl_post_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl_post_grid-9bb514c-8585\" class=\"pxl-grid pxl-portfolio-grid pxl-portfolio-grid-layout1 pxl-portfolio-style1 df pxl-check-scroll pxl-effect--3d overlay\" data-start-page=\"1\" data-max-pages=\"3\" data-total=\"21\" data-perpage=\"8\" data-next-link=\"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/pages\/4332\/page\/2\/\" data-loadmore=\"{&quot;tax&quot;:[&quot;portfolio-category&quot;],&quot;post_type&quot;:&quot;portfolio&quot;,&quot;layout&quot;:&quot;portfolio-1&quot;,&quot;startPage&quot;:1,&quot;maxPages&quot;:3,&quot;total&quot;:21,&quot;filter&quot;:&quot;false&quot;,&quot;filter_type&quot;:&quot;normal&quot;,&quot;perpage&quot;:8,&quot;nextLink&quot;:&quot;https:\\\/\\\/dezetoro.com\\\/br\\\/wp-json\\\/wp\\\/v2\\\/pages\\\/4332\\\/page\\\/2\\\/&quot;,&quot;source&quot;:&quot;&quot;,&quot;orderby&quot;:&quot;date&quot;,&quot;order&quot;:&quot;asc&quot;,&quot;num_words&quot;:25,&quot;limit&quot;:8,&quot;post_ids&quot;:[],&quot;col_xl&quot;:3,&quot;col_lg&quot;:4,&quot;col_md&quot;:6,&quot;col_sm&quot;:12,&quot;col_xs&quot;:12,&quot;pagination_type&quot;:&quot;loadmore&quot;,&quot;post_style_l1&quot;:&quot;df&quot;,&quot;show_excerpt&quot;:&quot;true&quot;,&quot;show_button&quot;:&quot;true&quot;,&quot;show_category&quot;:&quot;true&quot;,&quot;img_size&quot;:&quot;&quot;,&quot;grid_masonry&quot;:&quot;&quot;,&quot;pxl_animate&quot;:&quot;&quot;}\" data-layout=\"masonry\">\n    \n    <div class=\"pxl-grid-inner pxl-grid-masonry row\" data-gutter=\"15\">\n        <div class=\"grid-sizer col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12\"><\/div>\n                        <div class=\"pxl-grid-item col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12 identidade-visual sites\">\n\n                    <div class=\"pxl-post--inner \" data-wow-duration=\"1.2s\">\n                        <div class=\"pxl-post--featured \">\n                            <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/arwo\/\">   \n                                <img fetchpriority=\"high\" decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2025\/06\/arwo_1-767x619.png\" width=\"767\" height=\"619\" alt=\"arwo_1\" title=\"arwo_1\" \/>                            <\/a>    \n                            <div class=\"pxl-post-content-hide\">\n                                <div class=\"pxl-post-content-top\">\n                                                                                                                <div class=\"pxl-post--content\">\n                                                                                            A Arwo \u00e9 uma marca especializada em m\u00f3veis autorais em madeira maci\u00e7a, que combina design sofisticado, sensibilidade artesanal e respeito pela natureza para criar pe\u00e7as&hellip;                                                                                    <\/div>\n                                                                    <\/div>\n                                                                    <a class=\"btn-readmore\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/arwo\/\">   \n                                      <span class=\"button-arrow-hover\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                    <\/span>\n                                <\/a>\n                                                    <\/div>\n                        <a class=\"pxl-item--overlay\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/arwo\/\">   \n                        <\/a>  \n                    <\/div>\n                                            <div class=\"pxl-post--holder\">\n                                                            <div class=\"pxl-post--category\">\n                                    <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/identidade-visual\/\" rel=\"tag\">Identidade visual<\/a> \/ <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/sites\/\" rel=\"tag\">Sites<\/a>                                <\/div>\n                                                        <h5 class=\"pxl-post--title\">\n                                <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/arwo\/\">   \n                                    Arwo                                <\/a>    \n                            <\/h5>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12 sites\">\n\n                    <div class=\"pxl-post--inner \" data-wow-duration=\"1.2s\">\n                        <div class=\"pxl-post--featured \">\n                            <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/quite-agora\/\">   \n                                <img decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/01\/sadsdaasdasd-767x619.png\" width=\"767\" height=\"619\" alt=\"sadsdaasdasd\" title=\"sadsdaasdasd\" \/>                            <\/a>    \n                            <div class=\"pxl-post-content-hide\">\n                                <div class=\"pxl-post-content-top\">\n                                                                                                                <div class=\"pxl-post--content\">\n                                                                                            A Quite Agora \u00e9 uma empresa focada em solu\u00e7\u00f5es pr\u00e1ticas para regulariza\u00e7\u00e3o e quita\u00e7\u00e3o de pend\u00eancias, oferecendo clareza, agilidade e orienta\u00e7\u00e3o ao cliente em todo&hellip;                                                                                    <\/div>\n                                                                    <\/div>\n                                                                    <a class=\"btn-readmore\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/quite-agora\/\">   \n                                      <span class=\"button-arrow-hover\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                    <\/span>\n                                <\/a>\n                                                    <\/div>\n                        <a class=\"pxl-item--overlay\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/quite-agora\/\">   \n                        <\/a>  \n                    <\/div>\n                                            <div class=\"pxl-post--holder\">\n                                                            <div class=\"pxl-post--category\">\n                                    <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/sites\/\" rel=\"tag\">Sites<\/a>                                <\/div>\n                                                        <h5 class=\"pxl-post--title\">\n                                <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/quite-agora\/\">   \n                                    Quite Agora                                <\/a>    \n                            <\/h5>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12 sites\">\n\n                    <div class=\"pxl-post--inner \" data-wow-duration=\"1.2s\">\n                        <div class=\"pxl-post--featured \">\n                            <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/gran-cavalheiro\/\">   \n                                <img decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/01\/sadsadasd-1-767x619.png\" width=\"767\" height=\"619\" alt=\"sadsadasd\" title=\"sadsadasd\" \/>                            <\/a>    \n                            <div class=\"pxl-post-content-hide\">\n                                <div class=\"pxl-post-content-top\">\n                                                                                                                <div class=\"pxl-post--content\">\n                                                                                            A Gran Cavalheiro \u00e9 uma barbearia que une tradi\u00e7\u00e3o, estilo e cuidado masculino, oferecendo servi\u00e7os cl\u00e1ssicos e um atendimento pensado para proporcionar uma experi\u00eancia completa.&hellip;                                                                                    <\/div>\n                                                                    <\/div>\n                                                                    <a class=\"btn-readmore\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/gran-cavalheiro\/\">   \n                                      <span class=\"button-arrow-hover\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                    <\/span>\n                                <\/a>\n                                                    <\/div>\n                        <a class=\"pxl-item--overlay\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/gran-cavalheiro\/\">   \n                        <\/a>  \n                    <\/div>\n                                            <div class=\"pxl-post--holder\">\n                                                            <div class=\"pxl-post--category\">\n                                    <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/sites\/\" rel=\"tag\">Sites<\/a>                                <\/div>\n                                                        <h5 class=\"pxl-post--title\">\n                                <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/gran-cavalheiro\/\">   \n                                    Gran Cavalheiro                                <\/a>    \n                            <\/h5>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12 sites\">\n\n                    <div class=\"pxl-post--inner \" data-wow-duration=\"1.2s\">\n                        <div class=\"pxl-post--featured \">\n                            <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/vtn-seguros\/\">   \n                                <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/01\/dsffsddsfdfs-767x619.png\" width=\"767\" height=\"619\" alt=\"dsffsddsfdfs\" title=\"dsffsddsfdfs\" \/>                            <\/a>    \n                            <div class=\"pxl-post-content-hide\">\n                                <div class=\"pxl-post-content-top\">\n                                                                                                                <div class=\"pxl-post--content\">\n                                                                                            A VTN Corretora de Seguros atua oferecendo solu\u00e7\u00f5es completas em seguros, com foco em prote\u00e7\u00e3o, transpar\u00eancia e atendimento personalizado. Sua presen\u00e7a digital precisava refletir confian\u00e7a,&hellip;                                                                                    <\/div>\n                                                                    <\/div>\n                                                                    <a class=\"btn-readmore\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/vtn-seguros\/\">   \n                                      <span class=\"button-arrow-hover\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                    <\/span>\n                                <\/a>\n                                                    <\/div>\n                        <a class=\"pxl-item--overlay\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/vtn-seguros\/\">   \n                        <\/a>  \n                    <\/div>\n                                            <div class=\"pxl-post--holder\">\n                                                            <div class=\"pxl-post--category\">\n                                    <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/sites\/\" rel=\"tag\">Sites<\/a>                                <\/div>\n                                                        <h5 class=\"pxl-post--title\">\n                                <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/vtn-seguros\/\">   \n                                    VTN Seguros                                <\/a>    \n                            <\/h5>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12 sites\">\n\n                    <div class=\"pxl-post--inner \" data-wow-duration=\"1.2s\">\n                        <div class=\"pxl-post--featured \">\n                            <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/marcon\/\">   \n                                <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/01\/sadasdasdasd-767x619.png\" width=\"767\" height=\"619\" alt=\"sadasdasdasd\" title=\"sadasdasdasd\" \/>                            <\/a>    \n                            <div class=\"pxl-post-content-hide\">\n                                <div class=\"pxl-post-content-top\">\n                                                                                                                <div class=\"pxl-post--content\">\n                                                                                            O Marcon no Campo \u00e9 um projeto voltado ao agroneg\u00f3cio, com foco na viv\u00eancia, no conte\u00fado e na presen\u00e7a direta no campo. A proposta exige&hellip;                                                                                    <\/div>\n                                                                    <\/div>\n                                                                    <a class=\"btn-readmore\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/marcon\/\">   \n                                      <span class=\"button-arrow-hover\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                    <\/span>\n                                <\/a>\n                                                    <\/div>\n                        <a class=\"pxl-item--overlay\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/marcon\/\">   \n                        <\/a>  \n                    <\/div>\n                                            <div class=\"pxl-post--holder\">\n                                                            <div class=\"pxl-post--category\">\n                                    <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/sites\/\" rel=\"tag\">Sites<\/a>                                <\/div>\n                                                        <h5 class=\"pxl-post--title\">\n                                <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/marcon\/\">   \n                                    Marcon                                <\/a>    \n                            <\/h5>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12 sites\">\n\n                    <div class=\"pxl-post--inner \" data-wow-duration=\"1.2s\">\n                        <div class=\"pxl-post--featured \">\n                            <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/ekora\/\">   \n                                <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/01\/dsffdssdfdsfdfs-767x619.png\" width=\"767\" height=\"619\" alt=\"dsffdssdfdsfdfs\" title=\"dsffdssdfdsfdfs\" \/>                            <\/a>    \n                            <div class=\"pxl-post-content-hide\">\n                                <div class=\"pxl-post-content-top\">\n                                                                                                                <div class=\"pxl-post--content\">\n                                                                                            A Ekora \u00e9 uma empresa focada em solu\u00e7\u00f5es estrat\u00e9gicas e intelig\u00eancia aplicada a neg\u00f3cios, com atua\u00e7\u00e3o orientada a dados, an\u00e1lise e tomada de decis\u00e3o. A&hellip;                                                                                    <\/div>\n                                                                    <\/div>\n                                                                    <a class=\"btn-readmore\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/ekora\/\">   \n                                      <span class=\"button-arrow-hover\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                    <\/span>\n                                <\/a>\n                                                    <\/div>\n                        <a class=\"pxl-item--overlay\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/ekora\/\">   \n                        <\/a>  \n                    <\/div>\n                                            <div class=\"pxl-post--holder\">\n                                                            <div class=\"pxl-post--category\">\n                                    <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/sites\/\" rel=\"tag\">Sites<\/a>                                <\/div>\n                                                        <h5 class=\"pxl-post--title\">\n                                <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/ekora\/\">   \n                                    Ekora                                <\/a>    \n                            <\/h5>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12 sites\">\n\n                    <div class=\"pxl-post--inner \" data-wow-duration=\"1.2s\">\n                        <div class=\"pxl-post--featured \">\n                            <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/edge-consultoria\/\">   \n                                <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/01\/sdadsasdaasd-767x619.png\" width=\"767\" height=\"619\" alt=\"sdadsasdaasd\" title=\"sdadsasdaasd\" \/>                            <\/a>    \n                            <div class=\"pxl-post-content-hide\">\n                                <div class=\"pxl-post-content-top\">\n                                                                                                                <div class=\"pxl-post--content\">\n                                                                                            A Edge Consultoria \u00e9 uma empresa focada em solu\u00e7\u00f5es estrat\u00e9gicas para neg\u00f3cios, atuando com an\u00e1lise, planejamento e suporte \u00e0 tomada de decis\u00e3o. Sua presen\u00e7a digital&hellip;                                                                                    <\/div>\n                                                                    <\/div>\n                                                                    <a class=\"btn-readmore\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/edge-consultoria\/\">   \n                                      <span class=\"button-arrow-hover\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                    <\/span>\n                                <\/a>\n                                                    <\/div>\n                        <a class=\"pxl-item--overlay\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/edge-consultoria\/\">   \n                        <\/a>  \n                    <\/div>\n                                            <div class=\"pxl-post--holder\">\n                                                            <div class=\"pxl-post--category\">\n                                    <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/sites\/\" rel=\"tag\">Sites<\/a>                                <\/div>\n                                                        <h5 class=\"pxl-post--title\">\n                                <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/edge-consultoria\/\">   \n                                    Edge Consultoria                                <\/a>    \n                            <\/h5>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                            <div class=\"pxl-grid-item col-xl-3 col-lg-4 col-md-6 col-sm-12 col-12 sites\">\n\n                    <div class=\"pxl-post--inner \" data-wow-duration=\"1.2s\">\n                        <div class=\"pxl-post--featured \">\n                            <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/lozeq\/\">   \n                                <img loading=\"lazy\" decoding=\"async\" class=\"no-lazyload \" src=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/01\/dsaasdsad-767x619.png\" width=\"767\" height=\"619\" alt=\"dsaasdsad\" title=\"dsaasdsad\" \/>                            <\/a>    \n                            <div class=\"pxl-post-content-hide\">\n                                <div class=\"pxl-post-content-top\">\n                                                                                                                <div class=\"pxl-post--content\">\n                                                                                            A Lozeq \u00e9 uma incorporadora que atua no desenvolvimento de empreendimentos imobili\u00e1rios, unindo planejamento, solidez e vis\u00e3o de longo prazo. Sua presen\u00e7a digital precisava refletir&hellip;                                                                                    <\/div>\n                                                                    <\/div>\n                                                                    <a class=\"btn-readmore\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/lozeq\/\">   \n                                      <span class=\"button-arrow-hover\">\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_1\" enable-background=\"new 0 0 1500 1500\" height=\"512\" viewBox=\"0 0 1500 1500\" width=\"512\"><g><path d=\"m1251.1 148.3h-728.4v-142.3h971.3v970l-142.3-.1v-727l-1245.1 1245.1-100.6-100.6z\"\/><\/g><\/svg>\n                                    <\/span>\n                                <\/a>\n                                                    <\/div>\n                        <a class=\"pxl-item--overlay\" href=\"https:\/\/dezetoro.com\/br\/portfolio\/lozeq\/\">   \n                        <\/a>  \n                    <\/div>\n                                            <div class=\"pxl-post--holder\">\n                                                            <div class=\"pxl-post--category\">\n                                    <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/sites\/\" rel=\"tag\">Sites<\/a>                                <\/div>\n                                                        <h5 class=\"pxl-post--title\">\n                                <a href=\"https:\/\/dezetoro.com\/br\/portfolio\/lozeq\/\">   \n                                    Lozeq                                <\/a>    \n                            <\/h5>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n                <\/div>\n                <div class=\"pxl-load-more\">\n            <span class=\"btn-grid-loadmore btn btn-default\">\n                <span class=\"pxl-loadmore-text pxl--btn-text\" data-text=\"Learn More Services\">view more<\/span>\n                <span class=\"pxl-load-icon\"><\/span>\n            <\/span>\n        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A Arwo \u00e9 uma marca especializada em m\u00f3veis autorais em madeira maci\u00e7a, que combina design sofisticado, sensibilidade artesanal e respeito pela natureza para criar pe\u00e7as&hellip; Identidade visual \/ Sites Arwo A Quite Agora \u00e9 uma empresa focada em solu\u00e7\u00f5es pr\u00e1ticas para regulariza\u00e7\u00e3o e quita\u00e7\u00e3o de pend\u00eancias, oferecendo clareza, agilidade e orienta\u00e7\u00e3o ao cliente em todo&hellip; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6348589,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ai_generated_summary":"","footnotes":""},"class_list":["post-4332","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6.1 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Projetos - Dezetoro<\/title>\n<meta name=\"description\" content=\"Conhe\u00e7a nossos projetos de cria\u00e7\u00e3o de sites institucionais e lojas virtuais desenvolvidos para empresas de diversos setores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dezetoro.com\/br\/projetos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projetos\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a nossos projetos de cria\u00e7\u00e3o de sites institucionais e lojas virtuais desenvolvidos para empresas de diversos setores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dezetoro.com\/br\/projetos\/\" \/>\n<meta property=\"og:site_name\" content=\"Dezetoro\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T22:37:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/06\/fav.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/projetos\\\/\",\"url\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/projetos\\\/\",\"name\":\"Projetos - Dezetoro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/projetos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/projetos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dezetoro.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/fav.png\",\"datePublished\":\"2025-06-14T01:53:24+00:00\",\"dateModified\":\"2026-06-03T22:37:00+00:00\",\"description\":\"Conhe\u00e7a nossos projetos de cria\u00e7\u00e3o de sites institucionais e lojas virtuais desenvolvidos para empresas de diversos setores.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/projetos\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dezetoro.com\\\/br\\\/projetos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/projetos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dezetoro.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/fav.png\",\"contentUrl\":\"https:\\\/\\\/dezetoro.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/fav.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/projetos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/dezetoro.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projetos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/\",\"name\":\"Dezetoro\",\"description\":\"Ag\u00eancia digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/#organization\",\"name\":\"Dezetoro\",\"url\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dezetoro.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/loader2.png\",\"contentUrl\":\"https:\\\/\\\/dezetoro.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/loader2.png\",\"width\":220,\"height\":45,\"caption\":\"Dezetoro\"},\"image\":{\"@id\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/dezetoro\\\/\",\"https:\\\/\\\/www.facebook.com\\\/dezetoro\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/dezetoro\"],\"description\":\"Especializada em criar sites, lojas virtuais e experi\u00eancias digitais estrat\u00e9gicas, pensadas para posicionar marcas, gerar oportunidades e impulsionar neg\u00f3cios.Unimos estrat\u00e9gia, design e tecnologia para transformar ideias em solu\u00e7\u00f5es digitais eficientes, com foco em performance, usabilidade e crescimento sustent\u00e1vel.\",\"email\":\"contato@dezetoro.com\",\"legalName\":\"Dezetoro\",\"foundingDate\":\"2010-10-21\",\"vatID\":\"12662603000138\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"diversityPolicy\":\"https:\\\/\\\/dezetoro.com\\\/br\\\/carreiras\\\/compromissos\\\/diversidade-equidade-e-inclusao-dei\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Projetos - Dezetoro","description":"Conhe\u00e7a nossos projetos de cria\u00e7\u00e3o de sites institucionais e lojas virtuais desenvolvidos para empresas de diversos setores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dezetoro.com\/br\/projetos\/","og_locale":"pt_BR","og_type":"article","og_title":"Projetos","og_description":"Conhe\u00e7a nossos projetos de cria\u00e7\u00e3o de sites institucionais e lojas virtuais desenvolvidos para empresas de diversos setores.","og_url":"https:\/\/dezetoro.com\/br\/projetos\/","og_site_name":"Dezetoro","article_modified_time":"2026-06-03T22:37:00+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/06\/fav.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dezetoro.com\/br\/projetos\/","url":"https:\/\/dezetoro.com\/br\/projetos\/","name":"Projetos - Dezetoro","isPartOf":{"@id":"https:\/\/dezetoro.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dezetoro.com\/br\/projetos\/#primaryimage"},"image":{"@id":"https:\/\/dezetoro.com\/br\/projetos\/#primaryimage"},"thumbnailUrl":"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/06\/fav.png","datePublished":"2025-06-14T01:53:24+00:00","dateModified":"2026-06-03T22:37:00+00:00","description":"Conhe\u00e7a nossos projetos de cria\u00e7\u00e3o de sites institucionais e lojas virtuais desenvolvidos para empresas de diversos setores.","breadcrumb":{"@id":"https:\/\/dezetoro.com\/br\/projetos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dezetoro.com\/br\/projetos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dezetoro.com\/br\/projetos\/#primaryimage","url":"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/06\/fav.png","contentUrl":"https:\/\/dezetoro.com\/wp-content\/uploads\/2026\/06\/fav.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/dezetoro.com\/br\/projetos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/dezetoro.com\/"},{"@type":"ListItem","position":2,"name":"Projetos"}]},{"@type":"WebSite","@id":"https:\/\/dezetoro.com\/br\/#website","url":"https:\/\/dezetoro.com\/br\/","name":"Dezetoro","description":"Ag\u00eancia digital","publisher":{"@id":"https:\/\/dezetoro.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dezetoro.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/dezetoro.com\/br\/#organization","name":"Dezetoro","url":"https:\/\/dezetoro.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dezetoro.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/dezetoro.com\/wp-content\/uploads\/2025\/12\/loader2.png","contentUrl":"https:\/\/dezetoro.com\/wp-content\/uploads\/2025\/12\/loader2.png","width":220,"height":45,"caption":"Dezetoro"},"image":{"@id":"https:\/\/dezetoro.com\/br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/dezetoro\/","https:\/\/www.facebook.com\/dezetoro\/","https:\/\/www.linkedin.com\/company\/dezetoro"],"description":"Especializada em criar sites, lojas virtuais e experi\u00eancias digitais estrat\u00e9gicas, pensadas para posicionar marcas, gerar oportunidades e impulsionar neg\u00f3cios.Unimos estrat\u00e9gia, design e tecnologia para transformar ideias em solu\u00e7\u00f5es digitais eficientes, com foco em performance, usabilidade e crescimento sustent\u00e1vel.","email":"contato@dezetoro.com","legalName":"Dezetoro","foundingDate":"2010-10-21","vatID":"12662603000138","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"diversityPolicy":"https:\/\/dezetoro.com\/br\/carreiras\/compromissos\/diversidade-equidade-e-inclusao-dei\/"}]}},"_links":{"self":[{"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/pages\/4332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/comments?post=4332"}],"version-history":[{"count":16,"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/pages\/4332\/revisions"}],"predecessor-version":[{"id":6347969,"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/pages\/4332\/revisions\/6347969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/media\/6348589"}],"wp:attachment":[{"href":"https:\/\/dezetoro.com\/br\/wp-json\/wp\/v2\/media?parent=4332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}